{"id":9128,"date":"2021-12-23T10:21:31","date_gmt":"2021-12-23T09:21:31","guid":{"rendered":"https:\/\/www.generationrobots.com\/blog\/?p=9128"},"modified":"2026-04-22T15:54:58","modified_gmt":"2026-04-22T13:54:58","slug":"dynamixel-p-servomotoren-zum-bau-von-mars-rovers","status":"publish","type":"post","link":"https:\/\/www.generationrobots.com\/blog\/de\/dynamixel-p-servomotoren-zum-bau-von-mars-rovers\/","title":{"rendered":"Dynamixel-P Servomotoren zum Bau von Mars-Rovers"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9128\" class=\"elementor elementor-9128\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-95f24ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"95f24ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52b6d840\" data-id=\"52b6d840\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-372681d6 elementor-widget elementor-widget-text-editor\" data-id=\"372681d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><p class=\"wp-block-paragraph\">Die Dynamixel Servomotoren von ROBOTIS bieten eine hohe Performance und Widerstandsf\u00e4higkeit und werden &#8211; insbesondere vom <strong>CNES<\/strong> (National Center for Space Studies) &#8211; f\u00fcr Prototypingzwecke im <strong>Bereich Weltraumrobotik<\/strong> eingesetzt.<\/p><p><\/p><p><\/p><p class=\"wp-block-paragraph\">Das CNES verwendet sie u. a. zur <strong>Entwicklung des terrestrischen Prototyps<\/strong> eines Erkundungsroboters, der zu Phobos &#8211; einem der zwei Monde des Planeten Mars &#8211; geschickt wird.<\/p><p><\/p><p><\/p><p class=\"wp-block-paragraph\"><strong>Die Aufgabe dieses kleinen Roboters<\/strong> besteht darin, die physikalischen Eigenschaften und die Zusammensetzung des Regoliths zu studieren, das die Oberfl\u00e4che von Phobos bedeckt.<\/p><p><\/p><p><\/p><h2 class=\"wp-block-heading\">Warum ist Phobos so interessant?<\/h2><p><\/p><p><\/p><p class=\"wp-block-paragraph\">Dieses Rover-Projekt, das aus einer Zusammenarbeit zwischen Frankreich und Deutschland hervorging, ist Teil der <strong><a class=\"catalogue\" title=\"MMX-Mission - Martian Moons Exploration\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Martian_Moons_Exploration\" rel=\"nofollow\">MMX-Mission<\/a><\/strong> MMX-Mission (Martian Moons Exploration) Mission der japanischen Weltraumbeh\u00f6rde JAXA.<\/p><p><\/p><p><\/p><p class=\"wp-block-paragraph\">Ziel der MMX-Mission besteht darin, die Entstehungsgeschichte der beiden Marsmonde besser zu verstehen. Indem wir die Monde n\u00e4her studieren, k\u00f6nnen wir das Entstehungsszenario der Planeten des Sonnensystems besser verstehen und vor allem <strong>mehr \u00fcber die Herkunft von Wasser auf der Erde erfahren<\/strong>. Zu diesem Zweck ist die japanische Sonde mit zahlreichen wissenschaftlichen Instrumenten ausgestattet. Sie wird nacheinander auf den beiden Monden landen, um einige Gramm Regolith zu sammeln. Daraufhin werden diese in einer Wiedereintrittskapsel zur Erde zur\u00fcckgebracht und dort untersucht.<\/p><p><\/p><p><\/p><p class=\"wp-block-paragraph\">Der kleine Rover wird von der MMX-Sonde w\u00e4hrend eines \u00dcberflugs in sehr geringer H\u00f6he auf die Oberfl\u00e4che von Phobos fallen gelassen. Der Rover soll einhundert Tage lang im Einsatz bleiben.<\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-798140b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"798140b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-094ec02\" data-id=\"094ec02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-020d88e elementor-widget elementor-widget-video\" data-id=\"020d88e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/ZiZn3VID8_I&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7690930 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7690930\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d5b4577\" data-id=\"d5b4577\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5d43ce elementor-widget elementor-widget-text-editor\" data-id=\"d5d43ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Es ist anzumerken, dass die beiden kleinen Monde bei der Eroberung von Mars durch den Menschen eine wichtige Rolle spielen k\u00f6nnten. Sie dienen als Relaisstationen zwischen interplanetaren Reisen und der Landung. Das Prinzip ist das gleiche wie beim Apollo-Modul, das der Landef\u00e4hre Eagle im Mondorbit im Jahr 1969 als Relais diente. Die MMX-Mission soll <strong>2024<\/strong> von der Basis Tenegashima aus <strong>starten<\/strong>. Die Probe soll die Erde ca. 2029 erreichen.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading --><\/p>\n<h2>Die Mission der deutsch-franz\u00f6sischen Partnerschaft: einen autonomen Rover entwickeln, der nur 25 kg wiegt<\/h2>\n<p><!-- \/wp:heading --><!-- wp:heading {\"level\":3} --><\/p>\n<h3>Die deutsche Mission<\/h3>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>Das Deutsche Zentrum f\u00fcr Luft- und Raumfahrt (<strong>DLR<\/strong>) besch\u00e4ftigt sich mit der <strong>Au\u00dfenstruktur<\/strong> des Rovers, den Komponenten, die seine Mobilit\u00e4t gew\u00e4hrleisten (Bein, Rad), sowie mit dem <strong>Mechanismus<\/strong>, das ihn von der Sonde <strong>trennt<\/strong>. Dar\u00fcber hinaus stellt das Zentrum zwei wissenschaftliche Instrumente bereit: ein <strong>Radiometer<\/strong> und ein <strong>Raman-Spektrometer<\/strong>.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} --><\/p>\n<h3>Die franz\u00f6sische Mission<\/h3>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>Das <strong>CNES<\/strong>, das franz\u00f6sische Zentrum f\u00fcr Weltraumforschung, arbeitet am <strong>Bordcomputer<\/strong> und an der entsprechenden <strong>Flugsoftware<\/strong>, der <strong>Stromversorgungskette<\/strong> (Solarmodul, Batterie, Wechselrichter) und der <strong>Funkverbindung<\/strong> zwischen dem Rover und der Sonde. Die franz\u00f6sischen Instrumente bestehen aus 4 <strong>hochaufl\u00f6senden Kameras<\/strong>.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1aab7dc7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1aab7dc7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-58300a42\" data-id=\"58300a42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75277d6f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"75277d6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/static.generation-robots.com\/img\/robot-assistant-astronaute-cnes-artemis.jpg\" title=\"\" alt=\"Mobiler Roboter LORA \u2013 Artemis-Mondmission\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6ad2a9b5\" data-id=\"6ad2a9b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b8d6ffe elementor-widget elementor-widget-heading\" data-id=\"4b8d6ffe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">WEITERE LEKT\u00dcRE<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4943f2c1 elementor-widget elementor-widget-heading\" data-id=\"4943f2c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Fallstudie: Raumfahrt<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a2af609 elementor-widget elementor-widget-heading\" data-id=\"2a2af609\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Entwicklung eines Assistenzroboters f\u00fcr zuk\u00fcnftige Astronauten der Artemis-Mondmission<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69f80cf2 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"69f80cf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"\/blog\/de\/cnes-fallstudie-projekt-eines-astronauten-assistenzroboters\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Fallstudie lesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e9629de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e9629de\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e09c5ed\" data-id=\"e09c5ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8cb620 elementor-widget elementor-widget-text-editor\" data-id=\"d8cb620\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Mechanische Architektur: Fokus auf Uprighting-Funktion<\/h2>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>Wir redeten \u00fcber diese Mission mit <strong>Jean Bertrand, dem CNES-Ingenieur, der f\u00fcr mechatronische Aspekte<\/strong> in der Robotikabteilung f\u00fcr planetare Exploration am Toulouser Zentrum f\u00fcr Raumfahrt verantwortlich zeichnet.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Bei der MMX-Mission war Jean Bertrand u. a. f\u00fcr die <strong>Fertigung des terrestrischen Modells<\/strong> des Rovers zust\u00e4ndig. Zum Motorisieren des Modells w\u00e4hlte er G\u00e9n\u00e9ration Robots, den Alleinvertriebsh\u00e4ndler von <a class=\"catalogue\" title=\"Dynamixel Servomotor\" href=\"\/de\/169-dynamixel-servomotoren\"><strong>Dynamixel Servomotoren<\/strong><\/a> in Frankreich, als Lieferanten.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Der Zweck des Funktionsmodells des Rovers besteht darin, die Selbstaufrichtfunktion (Engl. \u201e<strong>Uprighting<\/strong>\u201c) des MMX-Rovers zu testen.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} --><\/p>\n<h3>Wozu dient die Uprighting-Funktion?<\/h3>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>Wenn die MMX-Raumsonde \u00fcber Phobos in sehr geringer H\u00f6he (ca. 40 m) fliegt, wird sie den Rover so wie er ist, ohne jeglichen Schutz oder jegliches Bremssystem, fallen lassen. Da die Schwerkraft auf Phobos extrem gering ist, entspricht <strong>ein freier Fall aus einer H\u00f6he von 40 m einem Fall aus einer H\u00f6he von nur 6 cm auf der Erde<\/strong>.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Daraufhin wird der kleine Rover von der Oberfl\u00e4che so lange abprallen, bis er sich in einer <strong>zuf\u00e4lligen Position<\/strong> stabilisiert. Nachdem sich der Roboter stabilisiert hat, kommt die Uprighting-Funktion zum Einsatz.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Der Roboter f\u00fchrt diesen kritischen Vorgang <strong>autonom<\/strong> durch, denn eine Fernsteuerung von der Erde aus w\u00e4re w\u00e4hrend der gesamten Landephase v\u00f6llig unm\u00f6glich. Eine weitere Einschr\u00e4nkung: Dieser Vorgang kann nur mit <strong>einer einzigen Akkuladung<\/strong> durchgef\u00fchrt werden, da die Solarmodule in diesem Stadium auf der R\u00fcckseite des Rovers geklappt sind.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Die (mit R\u00e4dern an den Enden ausgestatteten) langen Beine des Roboters werden mithilfe von Motoren ausfahren. Diese Beine werden daraufhin als Hebel verwendet, die <strong>ihn zum Rollen bringen werden<\/strong>, so dass er schlie\u00dflich auf vier R\u00e4dern stehend seine Arbeitsposition einnimmt.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Die Uprighting-Sequenz funktioniert <strong>unabh\u00e4ngig von der Position, in der sich der Roboter<\/strong> auf dem Boden von Phobos stabilisiert. Sollte er mal umkippen und sich auf einer Seite wiederfinden, werden die Beine keine Hebelwirkung haben. Daher ist in der Sequenz die sogenannte \u201e<strong>Fallschirmspringer<\/strong>\u201c-Position enthalten, in der alle vier Beine des Rovers nach oben gerichtet sind. In dieser Position kann er sich &#8211; zumindest teilweise &#8211; zum eigenen Bauch neigen. So kann er sich durch einige aufeinanderfolgende Bewegungen seiner vier Beine wieder aufrichten.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Sind die Solarmodule, \u00fcber die der Roboter w\u00e4hrend der gesamten Mission mit Energie versorgt wird, an ihrem Platz, k\u00f6nnen sie sicher verwendet werden.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ac5dc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ac5dc0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-363caa7\" data-id=\"363caa7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa5a952 elementor-widget elementor-widget-video\" data-id=\"aa5a952\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/mCEzr-Rqt7E&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a48e21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a48e21\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-96fbc09\" data-id=\"96fbc09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb6a12d elementor-widget elementor-widget-text-editor\" data-id=\"cb6a12d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Ein terrestrischer Prototyp zum Testen und Validieren der Uprighting-Funktion<\/h2><p><!-- \/wp:heading --><\/p><p><!-- wp:paragraph --><\/p><p>Der Prototyp, der zur Durchf\u00fchrung von Tests und zur Validierung de Uprighting-Funktion dient, unterscheidet sich nat\u00fcrlich vom Roboter, der zu Phobos entsendet wird.<\/p><p><!-- \/wp:paragraph --><\/p><p><!-- wp:paragraph --><\/p><p>Die Schwerkraft auf Phobos ist <strong>2000 Mal niedriger<\/strong> als auf der Erde. Bei dem f\u00fcr Phobos entwickelten Rover w\u00fcrde <strong>das Risiko bestehen<\/strong>, beim Rollen unter Einwirkung der Erdanziehungskraft ganz <strong>schnell zerst\u00f6rt zu werden<\/strong>. Sein Chassis aus Carbon-Nida und seine d\u00fcnnen Beine (auch wenn sie aus Titan sind) w\u00fcrden St\u00f6\u00dfen nicht sehr lange standhalten k\u00f6nnen!<\/p><p><!-- \/wp:paragraph --><\/p><p><!-- wp:paragraph --><\/p><p>Im Vergleich zum echten Rover ist das Landmodell widerstandsf\u00e4hig und kosteng\u00fcnstig. Sein praktisch bruchfester Rahmen besteht aus <strong>Polycarbonat<\/strong>. Bei seinen Aktuatoren handelt es sich um <strong>Dynamixel Servomotoren<\/strong>, die zugleich widerstandsf\u00e4hig und sehr pr\u00e4zise sind.<\/p><p><!-- \/wp:paragraph --><\/p><p><!-- wp:heading {\"level\":3} --><\/p><h3>Die Vorteile der Dynamixel Servomotoren f\u00fcr das CNES<\/h3><p><!-- \/wp:heading --><\/p><p><!-- wp:paragraph --><\/p><p>F\u00fcr dieses Projekt sind Motoren mit unterschiedlichen Steuerungstypen (<strong>im Hinblick auf die Position oder Geschwindigkeit<\/strong>) erforderlich. Bei Dynamixel Servomotoren, die pr\u00e4zise und stabile PID-Steuerungen bieten, handelt es sich um eine native Funktion.<\/p><p><!-- \/wp:paragraph --><\/p><p><!-- wp:paragraph --><\/p><p>Dar\u00fcber hinaus bieten sie <strong>zahlreiche Konfigurationsparameter<\/strong>. Beispielsweise l\u00e4sst sich das Drehmoment ganz einfach begrenzen, um bei der Verwendung leistungsstarker Motoren &#8211; wie z. B. der <a class=\"catalogue\" title=\"Dynamixel-P Servomotoren\" href=\"\/de\/216-dynamixel-pro-plus-servomotoren\">Dynamixel-P<\/a> &#8211; die Sicherheit der Bediener zu gew\u00e4hrleisten. Wenn die Beine zum Einsatz kommen, ist das Drehmoment der Servos auf eine Leistung von 30 % oberhalb des zum Aufrichten des Roboters erforderlichen Drehmoments <strong>beschr\u00e4nkt<\/strong>.<\/p><p><!-- \/wp:paragraph --><\/p><p><!-- wp:paragraph --><\/p><p>Ein weiterer erheblicher Vorteil der Dynamixel Servomotoren bei dieser Mission: Sie lassen sich \u00fcber eine <strong>serielle UART-Verbindung<\/strong> steuern. Dies ist auch bei dem zu Phobos entsendeten Roboter der Fall. In dem Roboter wird <strong>SpaceWire<\/strong> verwendet &#8211; ein Computerbus, der historisch auf dem <strong>IEEE 1355 Standard basiert und heutzutage bei zahlreichen Weltraummissionen von NASA<\/strong>, ESA oder JAXA (japanische Weltraumbeh\u00f6rde) verwendet wird.<\/p><p><!-- \/wp:paragraph --><\/p><p><!-- wp:paragraph --><\/p><p>So lassen sich <strong>Computercodes zum Steuern der Motoren des Modells und des echten Rovers entwickeln, die \u00e4hnlich genug sind<\/strong>. Beispielsweise erm\u00f6glichen Dynamixel-Produkte wie das DLR-Lokomotionssystem die Wiederherstellung der aktuellen Geschwindigkeit und des aktuellen Drehmoments bei einer Frequenz von 10 Hz. Dies ist sehr wichtig, da die permanente \u00dcberwachung des Zustands der Aktuatoren eine der Hauptfunktionen des Uprighting-Algorithmus ist.<\/p><p><!-- \/wp:paragraph --><\/p><p><!-- wp:paragraph --><\/p><p>Ein weiterer Vorteil besteht darin, dass <strong>alle Servomotoren des Sortiments auf die gleiche Weise gesteuert werden. Dies vereinfacht das Testen mehrerer Servomotor-Modelle<\/strong> mit demselben Computercode und macht es m\u00f6glich, schnell zu bestimmen, welcher Servomotor f\u00fcr eine bestimmte Anwendung optimal ist.<\/p><p><!-- \/wp:paragraph --><\/p><p><!-- wp:paragraph --><\/p><p>So konnte das CNES-Team bei diesem Projekt ohne jegliche Probleme von <strong><a class=\"catalogue\" title=\"Servomotor Dynamixel MX-64AR\" href=\"\/de\/401862-servomotor-dynamixel-mx-64ar.html\">MX-64AR Servomotoren<\/a> <\/strong>beim ersten Prototyp auf die <a class=\"catalogue\" title=\"Servomotor Dynamixel PRO PLUS H54P-100-S500-R\" href=\"\/de\/403322-servomotor-dynamixel-pro-plus-h54p-100-s500-r.html\"><strong>Dynamixel-P (Modell PH54-100-S500-R<\/strong>)<\/a> beim endg\u00fcltigen Modell umsteigen.<\/p><p><!-- \/wp:paragraph --><\/p><p><!-- wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6a5724 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6a5724\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3ea52be\" data-id=\"3ea52be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b933ae elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8b933ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"436\" height=\"290\" src=\"https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/prototype-rover-phobos-mx64-ar.jpg\" class=\"attachment-full size-full wp-image-9076\" alt=\"Version du prototype avec les servos MX64-AR\" srcset=\"https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/prototype-rover-phobos-mx64-ar.jpg 436w, https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/prototype-rover-phobos-mx64-ar-300x200.jpg 300w\" sizes=\"(max-width: 436px) 100vw, 436px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\">Version des Prototyps mit MX64-AR-Servos<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1f36232\" data-id=\"1f36232\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f63073 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7f63073\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"436\" height=\"290\" src=\"https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/prototype-rover-phobos-ph54-100-s500-r.jpg\" class=\"attachment-full size-full wp-image-9075\" alt=\"Version du prototype avec les PH54-100-S500-R\" srcset=\"https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/prototype-rover-phobos-ph54-100-s500-r.jpg 436w, https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/prototype-rover-phobos-ph54-100-s500-r-300x200.jpg 300w\" sizes=\"(max-width: 436px) 100vw, 436px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\">Version des Prototyps mit PH54-100-S500-R<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae3d926 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae3d926\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3251dc1\" data-id=\"3251dc1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3a58bd elementor-widget elementor-widget-text-editor\" data-id=\"b3a58bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die einzige Einschr\u00e4nkung bestand in der Implementierung einer indizierten <strong>Adressierungstabelle<\/strong> in den Dynamixel-P Servomotoren, um diese unter Verwendung desselben Computercodes wie bei Dynamixel MX oder XM steuern zu k\u00f6nnen.<\/p><p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p><p>In der endg\u00fcltigen Version des Modells erm\u00f6glicht diese Korrespondenztabelle <strong>gemischte Ketten<\/strong>zwischen den Dynamixel Servomotoren der R\u00e4der (XM-Serie) und den Dynamixel-P Servomotoren (fr\u00fcher: Dynamixel Pro), die f\u00fcr die Beine verwendet werden.<\/p><p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p><p>Bei der im Modell eingesetzten Software hat sich das CNES f\u00fcr die <strong>Sprache C<\/strong> entschieden, um die <strong>gr\u00f6\u00dftm\u00f6gliche \u00c4hnlichkeit mit der Software des echten Rovers zu gew\u00e4hrleisten<\/strong>. C ist nicht unbedingt der einfachste Weg zum Steuern von Dynamixel Servomotoren. Dank des Software Development Kits (<strong>SDK<\/strong>) und den mitgelieferten <strong>Unterlagen<\/strong> des Herstellers ROBOTIS wird damit jeder C-Entwickler mit einigen Jahren Erfahrung jedoch fertig.<\/p><p><!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} --><\/p><h3>Auswahl an Dynamixel Servomotoren f\u00fcr den MMX-Rover-Prototyp<\/h3><p><!-- \/wp:heading --><!-- wp:heading {\"level\":4} --><\/p><h4>Motorisierung der R\u00e4der: XM430-W210-R Servomotoren<\/h4><p><!-- \/wp:heading --><!-- wp:paragraph --><\/p><p><strong>=&gt; Grund f\u00fcr die Wahl:<\/strong> hier ist die Gr\u00f6\u00dfe wichtig; ein starkes Drehmoment oder eine hohe Geschwindigkeit sind nicht erforderlich, sondern vielmehr kompakte Servos, die in die R\u00e4der eingebaut werden.<\/p><h4>Nutzung der Beine: MX-64AR Servomotoren, anschlie\u00dfend PH54-100-S500-R<\/h4><p><!-- \/wp:heading --><!-- wp:paragraph --><\/p><p><strong>=&gt; Grund f\u00fcr die Wahl:<\/strong> die ersten Tests wurden mit dem MX-64AR durchgef\u00fchrt. Da es aber Situationen geben wird, in denen das gesamte Gewicht des Modells von einem einzigen Servomotor getragen werden muss, fehlte es an Drehmoment. Die Servomotoren der Dynamixel-P Reihe erm\u00f6glichen eine ausreichende Leistung f\u00fcr jede Anwendung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9770a6b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9770a6b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-10a7312\" data-id=\"10a7312\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d84b159 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d84b159\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.generationrobots.com\/de\/402478-servomotor-xm430-w210-r.html\" tabindex=\"-1\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/servomoteur-dynamixel-xm430-w210-r-300x300-1-300x300.jpg\" class=\"attachment-medium size-medium wp-image-9049\" alt=\"Servomoteur Dynamixel XM430-W210-R\" srcset=\"https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/servomoteur-dynamixel-xm430-w210-r-300x300-1.jpg 300w, https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/servomoteur-dynamixel-xm430-w210-r-300x300-1-150x150.jpg 150w, https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/servomoteur-dynamixel-xm430-w210-r-300x300-1-140x140.jpg 140w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\"><a href=\"https:\/\/www.generationrobots.com\/de\/402478-servomotor-xm430-w210-r.html\">Servomotor XM430-W210-R<\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-eacc2ed\" data-id=\"eacc2ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1092065 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1092065\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.generationrobots.com\/de\/401862-servomotor-dynamixel-mx-64ar.html\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/servomoteur-dynamixel-mx-64ar-300x300-1.jpg\" class=\"attachment-full size-full wp-image-9050\" alt=\"Servomoteur Dynamixel MX-64AR\" srcset=\"https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/servomoteur-dynamixel-mx-64ar-300x300-1.jpg 300w, https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/servomoteur-dynamixel-mx-64ar-300x300-1-150x150.jpg 150w, https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/servomoteur-dynamixel-mx-64ar-300x300-1-140x140.jpg 140w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\"><a href=\"https:\/\/www.generationrobots.com\/de\/401862-servomotor-dynamixel-mx-64ar.html\">Servomotor MX-64AR<\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-429d317\" data-id=\"429d317\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4b8276 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b4b8276\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.generationrobots.com\/de\/403322-servomotor-dynamixel-pro-plus-h54p-100-s500-r.html\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/servomoteur-dynamixel-p-ph54-100-s500-r-300x300-1.jpg\" class=\"attachment-full size-full wp-image-9048\" alt=\"Servomoteur Dynamixel-P PH54-100-S500-R\" srcset=\"https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/servomoteur-dynamixel-p-ph54-100-s500-r-300x300-1.jpg 300w, https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/servomoteur-dynamixel-p-ph54-100-s500-r-300x300-1-150x150.jpg 150w, https:\/\/www.generationrobots.com\/blog\/wp-content\/uploads\/2021\/12\/servomoteur-dynamixel-p-ph54-100-s500-r-300x300-1-140x140.jpg 140w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\"><a href=\"https:\/\/www.generationrobots.com\/de\/403322-servomotor-dynamixel-pro-plus-h54p-100-s500-r.html\">Servomotor PH54-100-S500-R<\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74ecf424 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74ecf424\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ef2916\" data-id=\"9ef2916\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65b0a5ea elementor-widget elementor-widget-text-editor\" data-id=\"65b0a5ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 id=\"h-contactez-nous-pour-discuter-de-votre-projet-ou-pour-nous-demander-un-devis\">Kontaktieren Sie uns, um Ihr Projekt zu besprechen oder einen Kostenvoranschlag anzufordern<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c87146 elementor-button-align-center elementor-widget elementor-widget-form\" data-id=\"6c87146\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;N\\u00e4chste&quot;,&quot;step_previous_label&quot;:&quot;Vorherige&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" id=\"Blog\" name=\"telecharger-cas-client\" aria-label=\"telecharger-cas-client\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"9128\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"6c87146\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Dynamixel-P Servomotoren: Einsatz im Weltraum (Erkundung)\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"9128\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Name*\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmailadresse\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email*\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_e4636de elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_e4636de\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelefon\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_e4636de]\" id=\"form-field-field_e4636de\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Telefon\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-field_3aa81e4 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3aa81e4\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNachricht\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[field_3aa81e4]\" id=\"form-field-field_3aa81e4\" rows=\"4\" placeholder=\"Nachricht\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_01f6b2b elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_01f6b2b]\" id=\"form-field-field_01f6b2b\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\">\n\t\t\t\t<label for=\"form-field-field_01f6b2b\">Von Zeit zu Zeit m\u00f6chten wir Sie \u00fcber unsere Produkte und Dienstleistungen sowie andere Inhalte, die f\u00fcr Sie von Interesse sein k\u00f6nnten, informieren. Ich stimme zu, andere Benachrichtigungen von G\u00e9n\u00e9ration Robots zu erhalten. <b>Lesen sie unseren <a class=\"catalogue\" title=\"Datenschutzerkl\u00e4rung G\u00e9n\u00e9ration Robots\" href=\"\/de\/content\/120-Datenschutzerklaerung\">Datenschutzverfahren<\/a>.<\/b><\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_d7544db elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_d7544db\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LfccOcjAAAAAENMvgfWAyX3eUyTlTB9VNNzw3Ci\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm elementor-animation-grow\" type=\"submit\" id=\"contact_form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Senden<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Die Dynamixel Servomotoren von ROBOTIS bieten eine hohe Performance und Widerstandsf\u00e4higkeit und werden &#8211; insbesondere vom CNES (National Center for Space Studies) &#8211; f\u00fcr Prototypingzwecke im Bereich Weltraumrobotik eingesetzt. Das CNES verwendet sie u. a. zur Entwicklung des terrestrischen Prototyps eines Erkundungsroboters, der zu Phobos &#8211; einem der zwei Monde des Planeten Mars &#8211; geschickt[&#8230;]<br \/> <a class=\"button\" href=\"https:\/\/www.generationrobots.com\/blog\/de\/dynamixel-p-servomotoren-zum-bau-von-mars-rovers\/\" style=\"float:right;\">Read this article &gt;&gt;<\/a><\/p>\n","protected":false},"author":188,"featured_media":9084,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[10539],"tags":[],"class_list":["post-9128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kundenfalle-und-anwendungen"],"_links":{"self":[{"href":"https:\/\/www.generationrobots.com\/blog\/wp-json\/wp\/v2\/posts\/9128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.generationrobots.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.generationrobots.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.generationrobots.com\/blog\/wp-json\/wp\/v2\/users\/188"}],"replies":[{"embeddable":true,"href":"https:\/\/www.generationrobots.com\/blog\/wp-json\/wp\/v2\/comments?post=9128"}],"version-history":[{"count":19,"href":"https:\/\/www.generationrobots.com\/blog\/wp-json\/wp\/v2\/posts\/9128\/revisions"}],"predecessor-version":[{"id":23247,"href":"https:\/\/www.generationrobots.com\/blog\/wp-json\/wp\/v2\/posts\/9128\/revisions\/23247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.generationrobots.com\/blog\/wp-json\/wp\/v2\/media\/9084"}],"wp:attachment":[{"href":"https:\/\/www.generationrobots.com\/blog\/wp-json\/wp\/v2\/media?parent=9128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.generationrobots.com\/blog\/wp-json\/wp\/v2\/categories?post=9128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.generationrobots.com\/blog\/wp-json\/wp\/v2\/tags?post=9128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}